{"id":468,"count":2,"description":"","link":"https:\/\/conferenceinc.net\/post\/tag\/asia-conference\/","name":"Asia Conference","slug":"asia-conference","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Asia Conference Archives - Conference Inc.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/conferenceinc.net\/post\/tag\/asia-conference\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Asia Conference Archives - Conference Inc.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/conferenceinc.net\/post\/tag\/asia-conference\/\" \/>\n<meta property=\"og:site_name\" content=\"Conference Inc.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/conferenceinc.net\/post\/tag\/asia-conference\/\",\"url\":\"https:\/\/conferenceinc.net\/post\/tag\/asia-conference\/\",\"name\":\"Asia Conference Archives - Conference Inc.\",\"isPartOf\":{\"@id\":\"https:\/\/conferenceinc.net\/post\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/conferenceinc.net\/post\/tag\/asia-conference\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/conferenceinc.net\/post\/tag\/asia-conference\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/conferenceinc.net\/post\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Asia Conference\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/conferenceinc.net\/post\/#website\",\"url\":\"https:\/\/conferenceinc.net\/post\/\",\"name\":\"Conference Inc.\",\"description\":\"Conference News &amp; Articles\",\"publisher\":{\"@id\":\"https:\/\/conferenceinc.net\/post\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/conferenceinc.net\/post\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/conferenceinc.net\/post\/#organization\",\"name\":\"Conference Inc.\",\"url\":\"https:\/\/conferenceinc.net\/post\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/conferenceinc.net\/post\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/conferenceinc.net\/post\/wp-content\/uploads\/2025\/04\/conferenceinc-logo.png\",\"contentUrl\":\"https:\/\/conferenceinc.net\/post\/wp-content\/uploads\/2025\/04\/conferenceinc-logo.png\",\"width\":581,\"height\":206,\"caption\":\"Conference Inc.\"},\"image\":{\"@id\":\"https:\/\/conferenceinc.net\/post\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Asia Conference Archives - Conference Inc.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/conferenceinc.net\/post\/tag\/asia-conference\/","og_locale":"en_US","og_type":"article","og_title":"Asia Conference Archives - Conference Inc.","og_url":"https:\/\/conferenceinc.net\/post\/tag\/asia-conference\/","og_site_name":"Conference Inc.","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/conferenceinc.net\/post\/tag\/asia-conference\/","url":"https:\/\/conferenceinc.net\/post\/tag\/asia-conference\/","name":"Asia Conference Archives - Conference Inc.","isPartOf":{"@id":"https:\/\/conferenceinc.net\/post\/#website"},"breadcrumb":{"@id":"https:\/\/conferenceinc.net\/post\/tag\/asia-conference\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/conferenceinc.net\/post\/tag\/asia-conference\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/conferenceinc.net\/post\/"},{"@type":"ListItem","position":2,"name":"Asia Conference"}]},{"@type":"WebSite","@id":"https:\/\/conferenceinc.net\/post\/#website","url":"https:\/\/conferenceinc.net\/post\/","name":"Conference Inc.","description":"Conference News &amp; Articles","publisher":{"@id":"https:\/\/conferenceinc.net\/post\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/conferenceinc.net\/post\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/conferenceinc.net\/post\/#organization","name":"Conference Inc.","url":"https:\/\/conferenceinc.net\/post\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/conferenceinc.net\/post\/#\/schema\/logo\/image\/","url":"https:\/\/conferenceinc.net\/post\/wp-content\/uploads\/2025\/04\/conferenceinc-logo.png","contentUrl":"https:\/\/conferenceinc.net\/post\/wp-content\/uploads\/2025\/04\/conferenceinc-logo.png","width":581,"height":206,"caption":"Conference Inc."},"image":{"@id":"https:\/\/conferenceinc.net\/post\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/conferenceinc.net\/post\/wp-json\/wp\/v2\/tags\/468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conferenceinc.net\/post\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/conferenceinc.net\/post\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/conferenceinc.net\/post\/wp-json\/wp\/v2\/posts?tags=468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}